{"id":573,"count":0,"description":"","link":"https:\/\/bm-experts.de\/en\/tag\/wettbewerb-en\/","name":"Wettbewerb","slug":"wettbewerb-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wettbewerb Archive | BM-Experts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bm-experts.de\/en\/tag\/wettbewerb-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wettbewerb Archive | BM-Experts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bm-experts.de\/en\/tag\/wettbewerb-en\/\" \/>\n<meta property=\"og:site_name\" content=\"BM-Experts\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Uwe_BME\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/bm-experts.de\\\/en\\\/tag\\\/wettbewerb-en\\\/\",\"url\":\"https:\\\/\\\/bm-experts.de\\\/en\\\/tag\\\/wettbewerb-en\\\/\",\"name\":\"Wettbewerb Archive | BM-Experts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bm-experts.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bm-experts.de\\\/en\\\/tag\\\/wettbewerb-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bm-experts.de\\\/en\\\/tag\\\/wettbewerb-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/bm-experts.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wettbewerb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bm-experts.de\\\/#website\",\"url\":\"https:\\\/\\\/bm-experts.de\\\/\",\"name\":\"BM-Experts GmbH\",\"description\":\"B2B-Vertrieb in der Digitalen Transformation\",\"publisher\":{\"@id\":\"https:\\\/\\\/bm-experts.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bm-experts.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bm-experts.de\\\/#organization\",\"name\":\"BM-Experts GmbH\",\"url\":\"https:\\\/\\\/bm-experts.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bm-experts.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bm-experts.de\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/logo_BME.jpg\",\"contentUrl\":\"https:\\\/\\\/bm-experts.de\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/logo_BME.jpg\",\"width\":197,\"height\":70,\"caption\":\"BM-Experts GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/bm-experts.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pg\\\/BM-Experts-GmbH-712363085580693\",\"https:\\\/\\\/x.com\\\/Uwe_BME\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bm-experts-gmbh\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BMExpertsGmbH\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wettbewerb Archive | BM-Experts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bm-experts.de\/en\/tag\/wettbewerb-en\/","og_locale":"en_US","og_type":"article","og_title":"Wettbewerb Archive | BM-Experts","og_url":"https:\/\/bm-experts.de\/en\/tag\/wettbewerb-en\/","og_site_name":"BM-Experts","twitter_card":"summary_large_image","twitter_site":"@Uwe_BME","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/bm-experts.de\/en\/tag\/wettbewerb-en\/","url":"https:\/\/bm-experts.de\/en\/tag\/wettbewerb-en\/","name":"Wettbewerb Archive | BM-Experts","isPartOf":{"@id":"https:\/\/bm-experts.de\/#website"},"breadcrumb":{"@id":"https:\/\/bm-experts.de\/en\/tag\/wettbewerb-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/bm-experts.de\/en\/tag\/wettbewerb-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/bm-experts.de\/en\/"},{"@type":"ListItem","position":2,"name":"Wettbewerb"}]},{"@type":"WebSite","@id":"https:\/\/bm-experts.de\/#website","url":"https:\/\/bm-experts.de\/","name":"BM-Experts GmbH","description":"B2B-Vertrieb in der Digitalen Transformation","publisher":{"@id":"https:\/\/bm-experts.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bm-experts.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/bm-experts.de\/#organization","name":"BM-Experts GmbH","url":"https:\/\/bm-experts.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bm-experts.de\/#\/schema\/logo\/image\/","url":"https:\/\/bm-experts.de\/wp-content\/uploads\/2016\/10\/logo_BME.jpg","contentUrl":"https:\/\/bm-experts.de\/wp-content\/uploads\/2016\/10\/logo_BME.jpg","width":197,"height":70,"caption":"BM-Experts GmbH"},"image":{"@id":"https:\/\/bm-experts.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pg\/BM-Experts-GmbH-712363085580693","https:\/\/x.com\/Uwe_BME","https:\/\/www.linkedin.com\/company\/bm-experts-gmbh\/","https:\/\/www.youtube.com\/user\/BMExpertsGmbH"]}]}},"_links":{"self":[{"href":"https:\/\/bm-experts.de\/en\/wp-json\/wp\/v2\/tags\/573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bm-experts.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/bm-experts.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/bm-experts.de\/en\/wp-json\/wp\/v2\/posts?tags=573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}